{"id":6864,"date":"2021-02-25T14:49:52","date_gmt":"2021-02-25T06:49:52","guid":{"rendered":"https:\/\/www.xiazhi.co\/instructor-registration-page"},"modified":"2023-04-02T00:21:32","modified_gmt":"2023-04-01T16:21:32","slug":"instructor-registration","status":"publish","type":"page","link":"https:\/\/www.xiazhi.co\/en\/academy\/instructor-registration\/","title":{"rendered":"\u8bb2\u5e08\u6ce8\u518c"},"content":{"rendered":"<div id=\"tutor-registration-wrap\">\n\n\t\t\n\t\t<form method=\"post\" enctype=\"multipart\/form-data\" id=\"tutor-registration-form\" action=\"\">\n\n\t\t\t\n\t\t\t<input type=\"hidden\" id=\"_tutor_nonce\" name=\"_tutor_nonce\" value=\"44e546bee4\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/6864\" \/>\t\t\t<input type=\"hidden\" value=\"tutor_register_instructor\" name=\"tutor_action\"\/>\n\n\t\t\t\n\t\t\t<div class=\"tutor-form-row\">\n\t\t\t\t<div class=\"tutor-form-col-6\">\n\t\t\t\t\t<div class=\"tutor-form-group\">\n\t\t\t\t\t\t<label>\n\t\t\t\t\t\t\tFirst Name\t\t\t\t\t\t<\/label>\n\n\t\t\t\t\t\t<input type=\"text\" name=\"first_name\" value=\"\" placeholder=\"First Name\" required autocomplete=\"given-name\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tutor-form-col-6\">\n\t\t\t\t\t<div class=\"tutor-form-group\">\n\t\t\t\t\t\t<label>\n\t\t\t\t\t\t\tLast Name\t\t\t\t\t\t<\/label>\n\n\t\t\t\t\t\t<input type=\"text\" name=\"last_name\" value=\"\" placeholder=\"Last Name\" required autocomplete=\"family-name\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\n\t\t\t<\/div>\n\n\t\t\t<div class=\"tutor-form-row\">\n\n\t\t\t\t<div class=\"tutor-form-col-6\">\n\t\t\t\t\t<div class=\"tutor-form-group\">\n\t\t\t\t\t\t<label>\n\t\t\t\t\t\t\tUser Name\t\t\t\t\t\t<\/label>\n\n\t\t\t\t\t\t<input type=\"text\" name=\"user_login\" class=\"tutor_user_name\" value=\"\" placeholder=\"User Name\" required autocomplete=\"username\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tutor-form-col-6\">\n\t\t\t\t\t<div class=\"tutor-form-group\">\n\t\t\t\t\t\t<label>\n\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t<\/label>\n\n\t\t\t\t\t\t<input type=\"text\" name=\"email\" value=\"\" placeholder=\"E-Mail\" required autocomplete=\"email\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t\t\t<div class=\"tutor-form-row\">\n\t\t\t\t<div class=\"tutor-form-col-6\">\n\t\t\t\t\t<div class=\"tutor-form-group\">\n\t\t\t\t\t\t<div class=\"tutor-password-strength-checker\">\n\t\t\t\t\t\t\t<div class=\"tutor-password-field\">\n\t\t\t\t\t\t\t\t<label>\n\t\t\t\t\t\t\t\t\tPassword\t\t\t\t\t\t\t\t<\/label>\n\n\t\t\t\t\t\t\t\t<input class=\"password-checker\" id=\"tutor-new-password\" type=\"password\" name=\"password\" value=\"\" placeholder=\"Password\" required autocomplete=\"new-password\">\n\t\t\t\t\t\t\t\t<span class=\"show-hide-btn\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"tutor-password-strength-hint\">\n\t\t\t\t\t\t\t\t<div class=\"indicator\">\n\t\t\t\t\t\t\t\t\t<span class=\"weak\"><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"medium\"><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"strong\"><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"text tutor-fs-7 tutor-color-muted\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tutor-form-col-6\">\n\t\t\t\t\t<div class=\"tutor-form-group\">\n\t\t\t\t\t\t<label>\n\t\t\t\t\t\t\tPassword confirmation\t\t\t\t\t\t<\/label>\n\n\t\t\t\t\t\t<div class=\"tutor-form-wrap\">\n\t\t\t\t\t\t\t<span class=\"tutor-validation-icon tutor-icon-mark tutor-color-success tutor-form-icon tutor-form-icon-reverse\" style=\"display: none;\"><\/span>\n\t\t\t\t\t\t\t<input type=\"password\" name=\"password_confirmation\" value=\"\" placeholder=\"Password Confirmation\" required autocomplete=\"new-password\" style=\"margin-bottom: 0;\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"tutor-form-row\">\n\t\t\t\t<div class=\"tutor-form-col-12\">\n\t\t\t\t\t<div class=\"tutor-form-group\">\n\t\t\t\t\t\t\t\t<style>\n\t\t\t#registerform {\n\t\t\theight: 540px !important;\n\t\t\t\/* background: transparent; *\/\n\t\t}\n\t\t<\/style>\n\t\t<p class=\"logincust-reg-pass-wrap\">\n\t\t\t<label for=\"logincust-reg-pass\">Password<\/label>\n\t\t\t<input autocomplete=\"off\" name=\"logincust-reg-pass\" id=\"logincust-reg-pass\" class=\"input\" size=\"20\" value=\"\" type=\"password\" \/>\n\t\t<\/p>\n\t\t<p class=\"logincust-reg-pass-2-wrap\">\n\t\t\t<label for=\"logincust-reg-pass-2\">Confirm Password<\/label>\n\t\t\t<input autocomplete=\"off\" name=\"logincust-reg-pass-2\" id=\"logincust-reg-pass-2\" class=\"input\" size=\"20\" value=\"\" type=\"password\" \/>\n\t\t<\/p>\n      \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div> \n\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"tutor-form-row tutor-mb-24\">\n\t\t\t\t\t<div class=\"tutor-form-col-12\">\n\t\t\t\t\t\t<div class=\"tutor-d-flex tutor-gap-1 tutor-align-center\">\n\t\t\t\t\t\t\t<div class=\"tutor-form-wrap\">\n\t\t\t\t\t\t\t\t<input type=\"checkbox\" id=\"tutor-terms-conditions\" name=\"terms_conditions\" required>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<label for=\"tutor-terms-conditions\">\n\t\t\t\t\t\t\t\tBy signing up, you agree to the <a target=\"_blank\" href=\"https:\/\/www.xiazhi.co\/en\/company\/legal\/website-terms-of-service\/\" title=\"Terms and Conditions\">Terms and Conditions<\/a>\n\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div> \n\t\t\t\n\t\t\t<div>\n\t\t\t\t<button type=\"submit\" name=\"tutor_register_instructor_btn\" value=\"register\" class=\"tutor-btn tutor-btn-primary tutor-btn-block\">Register as instructor<\/button>\n\t\t\t<\/div>\n\t\t\t\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\t\t\t\t<style>\n\t\t\t#tutor-pro-twitter-login {\n\t\t\t\twidth: 400px; background-color: #00acee; border-color: #00acee; font-weight: bold;\n\t\t\t}\n\t\t<\/style>\n\t\t<div id=\"tutor-pro-social-authentication\" class=\"tutor-pt-24 tutor-d-flex tutor-flex-column tutor-align-center tutor-border-top-light\" style=\"gap: 10px;\">\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>First Name Last Name User Name E-Mail Password Password [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27248,"parent":7543,"menu_order":610,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6864","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/pages\/6864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/comments?post=6864"}],"version-history":[{"count":0,"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/pages\/6864\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/pages\/7543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/media\/27248"}],"wp:attachment":[{"href":"https:\/\/www.xiazhi.co\/en\/wp-json\/wp\/v2\/media?parent=6864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}